{"id":1652,"date":"2017-08-15T23:46:11","date_gmt":"2017-08-15T21:46:11","guid":{"rendered":"https:\/\/vielhuber.de\/?p=1652"},"modified":"2017-08-15T23:49:41","modified_gmt":"2017-08-15T21:49:42","slug":"wahrscheinlichkeiten-an-der-analoguhr","status":"publish","type":"post","link":"https:\/\/vielhuber.de\/blog\/wahrscheinlichkeiten-an-der-analoguhr\/","title":{"rendered":"Wahrscheinlichkeiten an der Analoguhr"},"content":{"rendered":"<p>In wie viel % der Zeit eines Tages befinden sich alle drei Zeiger einer analogen Uhr in der rechten H\u00e4lfte des Ziffernblattes? Zun\u00e4chst betrachtet man den Stundenzeiger, der in 12 von 24 Stunden jeweils auf der rechten Seite weilt (50%). Von dieser Zeit befindet sich der Minutenzeiger in 6 von 12 Stunden auf der rechten Seite (25%). Von diesen 6 Stunden verbringt der Sekundenzeiger 3 Stunden auf der rechten Seite (12.5%).<\/p>\n<p><!--more--><\/p>\n<p>Diese intuitive Erkl\u00e4rung l\u00e4sst sich auch leicht beweisen:<\/p>\n<p class=\"githubgist\" data-gist-file=\"proof.php\">f087c22406fdf4ea6fb9b195551be358<\/p>\n<p data-gist-file=\"proof.php\">Die Wahrscheinlichkeit gilt nicht nur f\u00fcr die rechte H\u00e4lfte des Ziffernblattes, sondern f\u00fcr jede beliebige H\u00e4lfte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In wie viel % der Zeit eines Tages befinden sich alle drei Zeiger einer analogen Uhr in der rechten H\u00e4lfte des Ziffernblattes? Zun\u00e4chst betrachtet man den Stundenzeiger, der in 12 von 24 Stunden jeweils auf der rechten Seite weilt (50%). Von dieser Zeit befindet sich der Minutenzeiger in 6 von 12 Stunden auf der rechten [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"gtbabel_prevent_lngs":"","gtbabel_alt_lng":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1652","post","type-post","status-publish","format-standard","category-blog"],"acf":[],"yoast_head":"<title>Wahrscheinlichkeiten an der Analoguhr &#060; Vielhuber David<\/title>\n<meta name=\"description\" content=\"In wie viel % der Zeit eines Tages befinden sich alle drei Zeiger einer analogen Uhr in der rechten H\u00e4lfte des Ziffernblattes? Zun\u00e4chst betrachtet m...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vielhuber.de\/blog\/wahrscheinlichkeiten-an-der-analoguhr\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wahrscheinlichkeiten an der Analoguhr &#060; Vielhuber David\" \/>\n<meta property=\"og:description\" content=\"In wie viel % der Zeit eines Tages befinden sich alle drei Zeiger einer analogen Uhr in der rechten H\u00e4lfte des Ziffernblattes? Zun\u00e4chst betrachtet man den\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vielhuber.de\/blog\/wahrscheinlichkeiten-an-der-analoguhr\/\" \/>\n<meta property=\"og:site_name\" content=\"Vielhuber David\" \/>\n<meta property=\"article:published_time\" content=\"2017-08-15T21:46:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-08-15T21:49:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"552\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@vielhuber\" \/>\n<meta name=\"twitter:site\" content=\"@vielhuber\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"David\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/wahrscheinlichkeiten-an-der-analoguhr\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/wahrscheinlichkeiten-an-der-analoguhr\\\/\"},\"author\":{\"name\":\"David\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\"},\"headline\":\"Wahrscheinlichkeiten an der Analoguhr\",\"datePublished\":\"2017-08-15T21:46:11+00:00\",\"dateModified\":\"2017-08-15T21:49:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/wahrscheinlichkeiten-an-der-analoguhr\\\/\"},\"wordCount\":104,\"publisher\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\"},\"articleSection\":[\"Blog\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/wahrscheinlichkeiten-an-der-analoguhr\\\/\",\"url\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/wahrscheinlichkeiten-an-der-analoguhr\\\/\",\"name\":\"Wahrscheinlichkeiten an der Analoguhr &#060; Vielhuber David\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#website\"},\"datePublished\":\"2017-08-15T21:46:11+00:00\",\"dateModified\":\"2017-08-15T21:49:42+00:00\",\"description\":\"In wie viel % der Zeit eines Tages befinden sich alle drei Zeiger einer analogen Uhr in der rechten H\u00e4lfte des Ziffernblattes? Zun\u00e4chst betrachtet man den\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/wahrscheinlichkeiten-an-der-analoguhr\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vielhuber.de\\\/blog\\\/wahrscheinlichkeiten-an-der-analoguhr\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/wahrscheinlichkeiten-an-der-analoguhr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vielhuber.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wahrscheinlichkeiten an der Analoguhr\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#website\",\"url\":\"https:\\\/\\\/vielhuber.de\\\/\",\"name\":\"Vielhuber David\",\"description\":\"Full-Stack Developer\",\"publisher\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vielhuber.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\",\"name\":\"David\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\",\"url\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\",\"contentUrl\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\",\"width\":700,\"height\":552,\"caption\":\"David\"},\"logo\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/vielhuber\"]}]}<\/script>","yoast_head_json":{"title":"Wahrscheinlichkeiten an der Analoguhr &#060; Vielhuber David","description":"In wie viel % der Zeit eines Tages befinden sich alle drei Zeiger einer analogen Uhr in der rechten H\u00e4lfte des Ziffernblattes? Zun\u00e4chst betrachtet m...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vielhuber.de\/blog\/wahrscheinlichkeiten-an-der-analoguhr\/","og_locale":"de_DE","og_type":"article","og_title":"Wahrscheinlichkeiten an der Analoguhr &#060; Vielhuber David","og_description":"In wie viel % der Zeit eines Tages befinden sich alle drei Zeiger einer analogen Uhr in der rechten H\u00e4lfte des Ziffernblattes? Zun\u00e4chst betrachtet man den","og_url":"https:\/\/vielhuber.de\/blog\/wahrscheinlichkeiten-an-der-analoguhr\/","og_site_name":"Vielhuber David","article_published_time":"2017-08-15T21:46:11+00:00","article_modified_time":"2017-08-15T21:49:42+00:00","og_image":[{"width":700,"height":552,"url":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg","type":"image\/jpeg"}],"author":"David","twitter_card":"summary_large_image","twitter_creator":"@vielhuber","twitter_site":"@vielhuber","twitter_misc":{"Verfasst von":"David","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vielhuber.de\/blog\/wahrscheinlichkeiten-an-der-analoguhr\/#article","isPartOf":{"@id":"https:\/\/vielhuber.de\/blog\/wahrscheinlichkeiten-an-der-analoguhr\/"},"author":{"name":"David","@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef"},"headline":"Wahrscheinlichkeiten an der Analoguhr","datePublished":"2017-08-15T21:46:11+00:00","dateModified":"2017-08-15T21:49:42+00:00","mainEntityOfPage":{"@id":"https:\/\/vielhuber.de\/blog\/wahrscheinlichkeiten-an-der-analoguhr\/"},"wordCount":104,"publisher":{"@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef"},"articleSection":["Blog"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/vielhuber.de\/blog\/wahrscheinlichkeiten-an-der-analoguhr\/","url":"https:\/\/vielhuber.de\/blog\/wahrscheinlichkeiten-an-der-analoguhr\/","name":"Wahrscheinlichkeiten an der Analoguhr &#060; Vielhuber David","isPartOf":{"@id":"https:\/\/vielhuber.de\/#website"},"datePublished":"2017-08-15T21:46:11+00:00","dateModified":"2017-08-15T21:49:42+00:00","description":"In wie viel % der Zeit eines Tages befinden sich alle drei Zeiger einer analogen Uhr in der rechten H\u00e4lfte des Ziffernblattes? Zun\u00e4chst betrachtet man den","breadcrumb":{"@id":"https:\/\/vielhuber.de\/blog\/wahrscheinlichkeiten-an-der-analoguhr\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vielhuber.de\/blog\/wahrscheinlichkeiten-an-der-analoguhr\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/vielhuber.de\/blog\/wahrscheinlichkeiten-an-der-analoguhr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vielhuber.de\/"},{"@type":"ListItem","position":2,"name":"Wahrscheinlichkeiten an der Analoguhr"}]},{"@type":"WebSite","@id":"https:\/\/vielhuber.de\/#website","url":"https:\/\/vielhuber.de\/","name":"Vielhuber David","description":"Full-Stack Developer","publisher":{"@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vielhuber.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef","name":"David","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg","url":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg","contentUrl":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg","width":700,"height":552,"caption":"David"},"logo":{"@id":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg"},"sameAs":["https:\/\/x.com\/vielhuber"]}]}},"_links":{"self":[{"href":"https:\/\/vielhuber.de\/zu\/wp-json\/wp\/v2\/posts\/1652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vielhuber.de\/zu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vielhuber.de\/zu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vielhuber.de\/zu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vielhuber.de\/zu\/wp-json\/wp\/v2\/comments?post=1652"}],"version-history":[{"count":6,"href":"https:\/\/vielhuber.de\/zu\/wp-json\/wp\/v2\/posts\/1652\/revisions"}],"predecessor-version":[{"id":1658,"href":"https:\/\/vielhuber.de\/zu\/wp-json\/wp\/v2\/posts\/1652\/revisions\/1658"}],"wp:attachment":[{"href":"https:\/\/vielhuber.de\/zu\/wp-json\/wp\/v2\/media?parent=1652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vielhuber.de\/zu\/wp-json\/wp\/v2\/categories?post=1652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vielhuber.de\/zu\/wp-json\/wp\/v2\/tags?post=1652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}