{"id":2751,"date":"2020-09-16T02:04:54","date_gmt":"2020-09-16T00:04:54","guid":{"rendered":"https:\/\/vielhuber.de\/?p=2751"},"modified":"2020-09-16T02:14:59","modified_gmt":"2020-09-16T00:14:59","slug":"quick-tip-split-testing-mit-apache","status":"publish","type":"post","link":"https:\/\/vielhuber.de\/blog\/quick-tip-split-testing-mit-apache\/","title":{"rendered":"Quick Tip: Split Testing mit Apache"},"content":{"rendered":"\n<p>Man muss kein m\u00e4chtiges Tool wie <a href=\"https:\/\/optimize.google.com\" target=\"_blank\" rel=\"noreferrer noopener\">Google Optimize<\/a> f\u00fcr einfache URL-Split-Tests bem\u00fchen, sondern kann auch den Apachen per .htaccess l\u00f6sen. Das folgende Code-Snippet verteilt f\u00fcr die beiden Seiten https:\/\/vielhuber.de\/test1.php (Variante 1) und https:\/\/vielhuber.de\/test2.php (Variante 2) dessen Besucher gleichm\u00e4\u00dfig auf beide Versionen. Die Randomisierung erfolgt auf Basis der aktuellen Serverzeit.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"githubgist\" data-gist-file=\".htaccess\">4ab46765cc5456fb96ad18db79dcfaaa<\/p>\n\n\n\n<p>Wiederkehrende Besucher sehen (per Session Cookie) stets die zuletzt angezeigte Webseite. Das Konzept l\u00e4sst sich leicht auf mehrere Varianten oder eine zentrale URL, die an Unterseiten verteilt, erweitern.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Man muss kein m\u00e4chtiges Tool wie Google Optimize f\u00fcr einfache URL-Split-Tests bem\u00fchen, sondern kann auch den Apachen per .htaccess l\u00f6sen. Das folgende Code-Snippet verteilt f\u00fcr die beiden Seiten https:\/\/vielhuber.de\/test1.php (Variante 1) und https:\/\/vielhuber.de\/test2.php (Variante 2) dessen Besucher gleichm\u00e4\u00dfig auf beide Versionen. Die Randomisierung erfolgt auf Basis der aktuellen Serverzeit.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"gtbabel_prevent_lngs":"","gtbabel_alt_lng":"","footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-2751","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-blog"},"acf":[],"yoast_head":"<title>Quick Tip: Split Testing mit Apache &#060; Vielhuber David<\/title>\n<meta name=\"description\" content=\"Man muss kein m\u00e4chtiges Tool wie Google Optimize f\u00fcr einfache URL-Split-Tests bem\u00fchen, sondern kann auch den Apachen per .htaccess l\u00f6sen. Das folg...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vielhuber.de\/blog\/quick-tip-split-testing-mit-apache\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quick Tip: Split Testing mit Apache &#060; Vielhuber David\" \/>\n<meta property=\"og:description\" content=\"Man muss kein m\u00e4chtiges Tool wie Google Optimize f\u00fcr einfache URL-Split-Tests bem\u00fchen, sondern kann auch den Apachen per .htaccess l\u00f6sen. Das folgende\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vielhuber.de\/blog\/quick-tip-split-testing-mit-apache\/\" \/>\n<meta property=\"og:site_name\" content=\"Vielhuber David\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-16T00:04:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-16T00:14:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"552\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@vielhuber\" \/>\n<meta name=\"twitter:site\" content=\"@vielhuber\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"David\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/quick-tip-split-testing-mit-apache\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/quick-tip-split-testing-mit-apache\\\/\"},\"author\":{\"name\":\"David\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\"},\"headline\":\"Quick Tip: Split Testing mit Apache\",\"datePublished\":\"2020-09-16T00:04:54+00:00\",\"dateModified\":\"2020-09-16T00:14:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/quick-tip-split-testing-mit-apache\\\/\"},\"wordCount\":102,\"publisher\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\"},\"articleSection\":[\"Blog\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/quick-tip-split-testing-mit-apache\\\/\",\"url\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/quick-tip-split-testing-mit-apache\\\/\",\"name\":\"Quick Tip: Split Testing mit Apache &#060; Vielhuber David\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#website\"},\"datePublished\":\"2020-09-16T00:04:54+00:00\",\"dateModified\":\"2020-09-16T00:14:59+00:00\",\"description\":\"Man muss kein m\u00e4chtiges Tool wie Google Optimize f\u00fcr einfache URL-Split-Tests bem\u00fchen, sondern kann auch den Apachen per .htaccess l\u00f6sen. Das folgende\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/quick-tip-split-testing-mit-apache\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vielhuber.de\\\/blog\\\/quick-tip-split-testing-mit-apache\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/quick-tip-split-testing-mit-apache\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vielhuber.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quick Tip: Split Testing mit Apache\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#website\",\"url\":\"https:\\\/\\\/vielhuber.de\\\/\",\"name\":\"Vielhuber David\",\"description\":\"Full-Stack Developer\",\"publisher\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vielhuber.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\",\"name\":\"David\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\",\"url\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\",\"contentUrl\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\",\"width\":700,\"height\":552,\"caption\":\"David\"},\"logo\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/vielhuber\"]}]}<\/script>","yoast_head_json":{"title":"Quick Tip: Split Testing mit Apache &#060; Vielhuber David","description":"Man muss kein m\u00e4chtiges Tool wie Google Optimize f\u00fcr einfache URL-Split-Tests bem\u00fchen, sondern kann auch den Apachen per .htaccess l\u00f6sen. Das folg...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vielhuber.de\/blog\/quick-tip-split-testing-mit-apache\/","og_locale":"de_DE","og_type":"article","og_title":"Quick Tip: Split Testing mit Apache &#060; Vielhuber David","og_description":"Man muss kein m\u00e4chtiges Tool wie Google Optimize f\u00fcr einfache URL-Split-Tests bem\u00fchen, sondern kann auch den Apachen per .htaccess l\u00f6sen. Das folgende","og_url":"https:\/\/vielhuber.de\/blog\/quick-tip-split-testing-mit-apache\/","og_site_name":"Vielhuber David","article_published_time":"2020-09-16T00:04:54+00:00","article_modified_time":"2020-09-16T00:14:59+00:00","og_image":[{"width":700,"height":552,"url":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg","type":"image\/jpeg"}],"author":"David","twitter_card":"summary_large_image","twitter_creator":"@vielhuber","twitter_site":"@vielhuber","twitter_misc":{"Verfasst von":"David"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vielhuber.de\/blog\/quick-tip-split-testing-mit-apache\/#article","isPartOf":{"@id":"https:\/\/vielhuber.de\/blog\/quick-tip-split-testing-mit-apache\/"},"author":{"name":"David","@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef"},"headline":"Quick Tip: Split Testing mit Apache","datePublished":"2020-09-16T00:04:54+00:00","dateModified":"2020-09-16T00:14:59+00:00","mainEntityOfPage":{"@id":"https:\/\/vielhuber.de\/blog\/quick-tip-split-testing-mit-apache\/"},"wordCount":102,"publisher":{"@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef"},"articleSection":["Blog"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/vielhuber.de\/blog\/quick-tip-split-testing-mit-apache\/","url":"https:\/\/vielhuber.de\/blog\/quick-tip-split-testing-mit-apache\/","name":"Quick Tip: Split Testing mit Apache &#060; Vielhuber David","isPartOf":{"@id":"https:\/\/vielhuber.de\/#website"},"datePublished":"2020-09-16T00:04:54+00:00","dateModified":"2020-09-16T00:14:59+00:00","description":"Man muss kein m\u00e4chtiges Tool wie Google Optimize f\u00fcr einfache URL-Split-Tests bem\u00fchen, sondern kann auch den Apachen per .htaccess l\u00f6sen. Das folgende","breadcrumb":{"@id":"https:\/\/vielhuber.de\/blog\/quick-tip-split-testing-mit-apache\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vielhuber.de\/blog\/quick-tip-split-testing-mit-apache\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/vielhuber.de\/blog\/quick-tip-split-testing-mit-apache\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vielhuber.de\/"},{"@type":"ListItem","position":2,"name":"Quick Tip: Split Testing mit Apache"}]},{"@type":"WebSite","@id":"https:\/\/vielhuber.de\/#website","url":"https:\/\/vielhuber.de\/","name":"Vielhuber David","description":"Full-Stack Developer","publisher":{"@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vielhuber.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef","name":"David","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg","url":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg","contentUrl":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg","width":700,"height":552,"caption":"David"},"logo":{"@id":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg"},"sameAs":["https:\/\/x.com\/vielhuber"]}]}},"_links":{"self":[{"href":"https:\/\/vielhuber.de\/vi\/wp-json\/wp\/v2\/posts\/2751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vielhuber.de\/vi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vielhuber.de\/vi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vielhuber.de\/vi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vielhuber.de\/vi\/wp-json\/wp\/v2\/comments?post=2751"}],"version-history":[{"count":4,"href":"https:\/\/vielhuber.de\/vi\/wp-json\/wp\/v2\/posts\/2751\/revisions"}],"predecessor-version":[{"id":2756,"href":"https:\/\/vielhuber.de\/vi\/wp-json\/wp\/v2\/posts\/2751\/revisions\/2756"}],"wp:attachment":[{"href":"https:\/\/vielhuber.de\/vi\/wp-json\/wp\/v2\/media?parent=2751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vielhuber.de\/vi\/wp-json\/wp\/v2\/categories?post=2751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vielhuber.de\/vi\/wp-json\/wp\/v2\/tags?post=2751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}