{"id":2068,"date":"2018-11-27T16:20:28","date_gmt":"2018-11-27T15:20:28","guid":{"rendered":"https:\/\/vielhuber.de\/?p=2068"},"modified":"2020-07-13T21:15:28","modified_gmt":"2020-07-13T19:15:28","slug":"lamp-stack-mit-windows-wsl","status":"publish","type":"post","link":"https:\/\/vielhuber.de\/blog\/lamp-stack-mit-windows-wsl\/","title":{"rendered":"LAMP-Stack im Windows Subsystem for Linux"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Auf der Suche nach der optimalen Entwicklungsumgebung bieten sich unter Windows 10 neben Komplettl\u00f6sungen wie <a rel=\"noreferrer noopener\" aria-label=\"Auf der Suche nach einer Entwicklungsumgebung bieten sich unter Windows 10 neben Komplettl\u00f6sungen wie XAMPP, WAMP, LAMP und MAMP, einer nativen Installation von Hand auch alternative L\u00f6sungen mit Vagrant (Scotch Box) und Docker&nbsp;(Devilbox, Laradock) an. (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/www.apachefriends.org\/de\/index.html\" target=\"_blank\">XAMPP<\/a>, <a rel=\"noreferrer noopener\" aria-label=\"Auf der Suche nach einer Entwicklungsumgebung bieten sich unter Windows 10 neben Komplettl\u00f6sungen wie XAMPP, WAMP, LAMP und MAMP, einer nativen Installation von Hand auch alternative L\u00f6sungen mit Vagrant (Scotch Box) und Docker&nbsp;(Devilbox, Laradock) an. (\u00f6ffnet in neuem Tab)\" href=\"http:\/\/www.wampserver.com\/en\/\" target=\"_blank\">WAMP<\/a>&nbsp;und <a rel=\"noreferrer noopener\" aria-label=\"Auf der Suche nach einer Entwicklungsumgebung bieten sich unter Windows 10 neben Komplettl\u00f6sungen wie XAMPP, WAMP&nbsp;und MAMP, einer nativen Installation von Hand auch alternative L\u00f6sungen mit Vagrant (Scotch Box) und Docker&nbsp;(Devilbox, Laradock) an. (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/www.mamp.info\/de\/\" target=\"_blank\">MAMP<\/a>, einer <a rel=\"noreferrer noopener\" aria-label=\"Auf der Suche nach einer Entwicklungsumgebung bieten sich unter Windows 10 neben Komplettl\u00f6sungen wie XAMPP, WAMP&nbsp;und MAMP, einer nativen Installation von Hand auch alternative L\u00f6sungen mit Vagrant (Scotch Box) und Docker&nbsp;(Devilbox, Laradock) an. (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/superuser.com\/questions\/748117\/how-to-manually-install-apache-php-and-mysql-on-windows\" target=\"_blank\">nativen Installation von Hand<\/a> auch Virtualisierungs-L\u00f6sungen wie&nbsp;<a rel=\"noreferrer noopener\" aria-label=\"Auf der Suche nach einer Entwicklungsumgebung bieten sich neben Komplettl\u00f6sungen wie XAMPP, WAMP, LAMP und MAMP, einer nativen Installation von Hand auch alternative L\u00f6sungen mit Vagrant (Scotch Box) und Docker an. (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/www.vagrantup.com\/\" target=\"_blank\">Vagrant<\/a> (<a rel=\"noreferrer noopener\" aria-label=\"Auf der Suche nach einer Entwicklungsumgebung bieten sich neben Komplettl\u00f6sungen wie XAMPP, WAMP, LAMP und MAMP, einer nativen Installation von Hand auch alternative L\u00f6sungen mit Vagrant (Scotch Box) und Docker an. (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/box.scotch.io\/\" target=\"_blank\">Scotch Box<\/a>) und <a rel=\"noreferrer noopener\" aria-label=\"Auf der Suche nach einer Entwicklungsumgebung bieten sich neben Komplettl\u00f6sungen wie XAMPP, WAMP, LAMP und MAMP, einer nativen Installation von Hand auch alternative L\u00f6sungen mit Vagrant (Scotch Box) und Docker an. (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/www.docker.com\/\" target=\"_blank\">Docker<\/a>&nbsp;(<a rel=\"noreferrer noopener\" aria-label=\"Auf der Suche nach einer Entwicklungsumgebung bieten sich neben Komplettl\u00f6sungen wie XAMPP, WAMP, LAMP und MAMP, einer nativen Installation von Hand auch alternative L\u00f6sungen mit Vagrant (Scotch Box) und Docker&nbsp;(Devilbox, Laradock) an. (\u00f6ffnet in neuem Tab)\" href=\"http:\/\/devilbox.org\/\" target=\"_blank\">Devilbox<\/a>, <a rel=\"noreferrer noopener\" aria-label=\"Auf der Suche nach einer Entwicklungsumgebung bieten sich neben Komplettl\u00f6sungen wie XAMPP, WAMP, LAMP und MAMP, einer nativen Installation von Hand auch alternative L\u00f6sungen mit Vagrant (Scotch Box) und Docker&nbsp;(Devilbox, Laradock) an. (\u00f6ffnet in neuem Tab)\" href=\"http:\/\/laradock.io\/\" target=\"_blank\">Laradock<\/a>) an. Doch an meinen Anforderungen wie freier Konfigurierbarkeit, echte Wildcard-SSL-Zertifikate, Zugriff von allen Endger\u00e4ten im lokalen Netzwerk aus sowie hohe Stabilit\u00e4t und Performance scheiterten alle L\u00f6sungen \u2013 bis auf eine.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Ich habe mit allen Varianten (insbesondere mit Docker) in den letzten Monaten experimentiert und bin dabei an <a aria-label=\"Auf der Suche nach einer Entwicklungsumgebung bieten sich neben Komplettl\u00f6sungen wie XAMPP, WAMP, LAMP und MAMP, einer nativen Installation von Hand auch alternative L\u00f6sungen mit Vagrant (Scotch Box) und Docker\u00a0(Devilbox, Laradock) an. Ich habe mit allen L\u00f6sungen experimentiert und bin dabei an Lando h\u00e4ngen geblieben,\u00a0 (\u00f6ffnet in neuem Tab)\" rel=\"noreferrer noopener\" href=\"https:\/\/docs.devwithlando.io\/\" target=\"_blank\">Lando<\/a> h\u00e4ngen geblieben. Doch es stellte sich heraus, dass alle auf Docker (und Vagrant) basierenden L\u00f6sungen aus Performancegr\u00fcnden unter Windows und Mac bei Projekten mit <a aria-label=\"Ich habe mit allen L\u00f6sungen (insbesondere mit Docker) in den letzten Monaten experimentiert und bin dabei an Lando h\u00e4ngen geblieben. Doch es stellte sich heraus, dass alle auf Docker (und Vagrant) basierenden L\u00f6sungen aus Performancegr\u00fcnden unter Windows und Mac bei Projekten mit h\u00f6herer Dateianzahl nichts taugen. Es gibt hier und hier und hier und hier zahlreiche Threads, in denen die Ursache, m\u00f6gliche L\u00f6sungsans\u00e4tze etc. diskutiert werden. F\u00fcr mich waren das jeweils zu viele zu schluckende Pillen, sodass ich an den Anfang zur\u00fcckgekehrt bin und auf Linux von Hand einen LAMP-Stack aufsetzte. Unter Windows war das normalem Weg oder per Cygwin ein zun\u00e4chst haneb\u00fcchenes Unterfangen, bis ich es mit Windows WSL versuchte. (\u00f6ffnet in neuem Tab)\" rel=\"noreferrer noopener\" href=\"https:\/\/twitter.com\/vielhuber\/status\/932782602314043392\" target=\"_blank\">h\u00f6herer Dateianzahl<\/a> nichts taugen (ein Seitenaufruf dauerte ca. 25 Sekunden). Es gibt <a aria-label=\"Ich habe mit allen L\u00f6sungen (insbesondere mit Docker) in den letzten Monaten experimentiert und bin dabei an Lando h\u00e4ngen geblieben. Doch es stellte sich heraus, dass alle auf Docker (und Vagrant) basierenden L\u00f6sungen aus Performancegr\u00fcnden unter Windows und Mac bei Projekten mit h\u00f6herer Dateianzahl nichts taugen. Es gibt hier und hier und hier und hier zahlreiche Threads, in denen die Ursache, m\u00f6gliche L\u00f6sungsans\u00e4tze etc. diskutiert werden. F\u00fcr mich waren das jeweils zu viele zu schluckende Pillen, sodass ich an den Anfang zur\u00fcckgekehrt bin und auf Linux von Hand einen LAMP-Stack aufsetzte. Unter Windows war das normalem Weg oder per Cygwin ein zun\u00e4chst haneb\u00fcchenes Unterfangen, bis ich es mit Windows WSL versuchte. (\u00f6ffnet in neuem Tab)\" rel=\"noreferrer noopener\" href=\"https:\/\/github.com\/lando\/lando\/issues\/763\" target=\"_blank\">hier<\/a> und <a aria-label=\"Ich habe mit allen L\u00f6sungen (insbesondere mit Docker) in den letzten Monaten experimentiert und bin dabei an Lando h\u00e4ngen geblieben. Doch es stellte sich heraus, dass alle auf Docker (und Vagrant) basierenden L\u00f6sungen aus Performancegr\u00fcnden unter Windows und Mac bei Projekten mit h\u00f6herer Dateianzahl nichts taugen. Es gibt hier und hier und hier und hier zahlreiche Threads, in denen die Ursache, m\u00f6gliche L\u00f6sungsans\u00e4tze etc. diskutiert werden. F\u00fcr mich waren das jeweils zu viele zu schluckende Pillen, sodass ich an den Anfang zur\u00fcckgekehrt bin und auf Linux von Hand einen LAMP-Stack aufsetzte. Unter Windows war das normalem Weg oder per Cygwin ein zun\u00e4chst haneb\u00fcchenes Unterfangen, bis ich es mit Windows WSL versuchte. (\u00f6ffnet in neuem Tab)\" rel=\"noreferrer noopener\" href=\"https:\/\/github.com\/cytopia\/devilbox\/issues\/105\" target=\"_blank\">hier<\/a> und <a href=\"http:\/\/webcache.googleusercontent.com\/search?q=cache:https:\/\/forums.docker.com\/t\/file-access-in-mounted-volumes-extremely-slow-cpu-bound\/8076\" target=\"_blank\" aria-label=\"undefined (opens in a new tab)\" rel=\"noreferrer noopener\">hier<\/a>\u00a0zahlreiche Threads, in denen die Ursache und\u00a0<a aria-label=\"Ich habe mit allen L\u00f6sungen (insbesondere mit Docker) in den letzten Monaten experimentiert und bin dabei an Lando h\u00e4ngen geblieben. Doch es stellte sich heraus, dass alle auf Docker (und Vagrant) basierenden L\u00f6sungen aus Performancegr\u00fcnden unter Windows und Mac bei Projekten mit h\u00f6herer Dateianzahl nichts taugen. Es gibt hier und hier und hier\u00a0zahlreiche Threads, in denen die Ursache, m\u00f6gliche L\u00f6sungsans\u00e4tze etc. diskutiert werden. F\u00fcr mich waren das jeweils zu viele zu schluckende Pillen, sodass ich an den Anfang zur\u00fcckgekehrt bin und auf Linux von Hand einen LAMP-Stack aufsetzte. Unter Windows war das normalem Weg oder per Cygwin ein zun\u00e4chst haneb\u00fcchenes Unterfangen, bis ich es mit Windows WSL versuchte. (\u00f6ffnet in neuem Tab)\" rel=\"noreferrer noopener\" href=\"http:\/\/docker-sync.io\/\" target=\"_blank\">m\u00f6gliche L\u00f6sungsans\u00e4tze<\/a>\u00a0diskutiert werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr mich waren das jeweils zu viele zu schluckende Pillen \u2013 Dateien sollten nicht manuell synchronisiert werden, sondern einfach verf\u00fcgbar sein. Auch wollte ich nicht mehr zum jahrelang genutzten MAMP PRO zur\u00fcck (insbesondere unter Windows ein Graus). So kehrte ich wieder an den Anfang zur\u00fcck und versuche es nochmals nativ. Unter Windows war das auf normalem Weg oder per&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.cygwin.com\/\" target=\"_blank\">Cygwin<\/a>&nbsp;ein zun\u00e4chst haneb\u00fcchenes Unterfangen, bis ich es mit&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/de.wikipedia.org\/wiki\/Windows_Subsystem_for_Linux\" target=\"_blank\">WSL<\/a>&nbsp;versuchte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich hatte bereits in den letzten Monaten sehr positive Erfahrungen mit dem Windows Subsystem for Linux gemacht und nachdem s\u00e4mtliche LAMP-Services nach kurzem Test ohne Einschr\u00e4nkungen in Sachen Stabilit\u00e4t und Performance funktionierten, bin ich zu der Einsch\u00e4tzung gekommen, dass Microsoft hier Gro\u00dfes geleistet hat. Es folgt mein (sich laufend erweiterndes) Setup inkl. aller Scripte f\u00fcr meine aktuelle Entwicklungsumgebung unter Windows 10 Pro:<\/p>\n\n\n\n<p class=\"githubgist\" data-gist-file=\"README.md\">3d95982c87ac786700b6d602cd977234<\/p>\n\n\n\n<p class=\"githubgist\" data-gist-file=\"lamp\">3d95982c87ac786700b6d602cd977234<\/p>\n\n\n\n<p class=\"githubgist\" data-gist-file=\"start.bat\">3d95982c87ac786700b6d602cd977234<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Auf der Suche nach der optimalen Entwicklungsumgebung bieten sich unter Windows 10 neben Komplettl\u00f6sungen wie XAMPP, WAMP&nbsp;und MAMP, einer nativen Installation von Hand auch Virtualisierungs-L\u00f6sungen wie&nbsp;Vagrant (Scotch Box) und Docker&nbsp;(Devilbox, Laradock) an. Doch an meinen Anforderungen wie freier Konfigurierbarkeit, echte Wildcard-SSL-Zertifikate, Zugriff von allen Endger\u00e4ten im lokalen Netzwerk aus sowie hohe Stabilit\u00e4t und Performance scheiterten [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"gtbabel_prevent_lngs":"","gtbabel_alt_lng":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-2068","post","type-post","status-publish","format-standard","category-blog"],"acf":[],"yoast_head":"<title>LAMP-Stack im Windows Subsystem for Linux &#060; Vielhuber David<\/title>\n<meta name=\"description\" content=\"Auf der Suche nach der optimalen Entwicklungsumgebung bieten sich unter Windows 10 neben Komplettl\u00f6sungen wie XAMPP, WAMP&nbsp;und MAMP, einer native...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vielhuber.de\/blog\/lamp-stack-mit-windows-wsl\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LAMP-Stack im Windows Subsystem for Linux &#060; Vielhuber David\" \/>\n<meta property=\"og:description\" content=\"Auf der Suche nach der optimalen Entwicklungsumgebung bieten sich unter Windows 10 neben Komplettl\u00f6sungen wie XAMPP, WAMP&nbsp;und MAMP, einer nativen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vielhuber.de\/blog\/lamp-stack-mit-windows-wsl\/\" \/>\n<meta property=\"og:site_name\" content=\"Vielhuber David\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-27T15:20:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-13T19:15:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"552\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@vielhuber\" \/>\n<meta name=\"twitter:site\" content=\"@vielhuber\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"David\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/lamp-stack-mit-windows-wsl\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/lamp-stack-mit-windows-wsl\\\/\"},\"author\":{\"name\":\"David\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\"},\"headline\":\"LAMP-Stack im Windows Subsystem for Linux\",\"datePublished\":\"2018-11-27T15:20:28+00:00\",\"dateModified\":\"2020-07-13T19:15:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/lamp-stack-mit-windows-wsl\\\/\"},\"wordCount\":316,\"publisher\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\"},\"articleSection\":[\"Blog\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/lamp-stack-mit-windows-wsl\\\/\",\"url\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/lamp-stack-mit-windows-wsl\\\/\",\"name\":\"LAMP-Stack im Windows Subsystem for Linux &#060; Vielhuber David\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#website\"},\"datePublished\":\"2018-11-27T15:20:28+00:00\",\"dateModified\":\"2020-07-13T19:15:28+00:00\",\"description\":\"Auf der Suche nach der optimalen Entwicklungsumgebung bieten sich unter Windows 10 neben Komplettl\u00f6sungen wie XAMPP, WAMP&nbsp;und MAMP, einer nativen\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/lamp-stack-mit-windows-wsl\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vielhuber.de\\\/blog\\\/lamp-stack-mit-windows-wsl\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/lamp-stack-mit-windows-wsl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vielhuber.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LAMP-Stack im Windows Subsystem for Linux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#website\",\"url\":\"https:\\\/\\\/vielhuber.de\\\/\",\"name\":\"Vielhuber David\",\"description\":\"Full-Stack Developer\",\"publisher\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vielhuber.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\",\"name\":\"David\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\",\"url\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\",\"contentUrl\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\",\"width\":700,\"height\":552,\"caption\":\"David\"},\"logo\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/vielhuber\"]}]}<\/script>","yoast_head_json":{"title":"LAMP-Stack im Windows Subsystem for Linux &#060; Vielhuber David","description":"Auf der Suche nach der optimalen Entwicklungsumgebung bieten sich unter Windows 10 neben Komplettl\u00f6sungen wie XAMPP, WAMP&nbsp;und MAMP, einer native...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vielhuber.de\/blog\/lamp-stack-mit-windows-wsl\/","og_locale":"de_DE","og_type":"article","og_title":"LAMP-Stack im Windows Subsystem for Linux &#060; Vielhuber David","og_description":"Auf der Suche nach der optimalen Entwicklungsumgebung bieten sich unter Windows 10 neben Komplettl\u00f6sungen wie XAMPP, WAMP&nbsp;und MAMP, einer nativen","og_url":"https:\/\/vielhuber.de\/blog\/lamp-stack-mit-windows-wsl\/","og_site_name":"Vielhuber David","article_published_time":"2018-11-27T15:20:28+00:00","article_modified_time":"2020-07-13T19:15:28+00:00","og_image":[{"width":700,"height":552,"url":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg","type":"image\/jpeg"}],"author":"David","twitter_card":"summary_large_image","twitter_creator":"@vielhuber","twitter_site":"@vielhuber","twitter_misc":{"Verfasst von":"David","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vielhuber.de\/blog\/lamp-stack-mit-windows-wsl\/#article","isPartOf":{"@id":"https:\/\/vielhuber.de\/blog\/lamp-stack-mit-windows-wsl\/"},"author":{"name":"David","@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef"},"headline":"LAMP-Stack im Windows Subsystem for Linux","datePublished":"2018-11-27T15:20:28+00:00","dateModified":"2020-07-13T19:15:28+00:00","mainEntityOfPage":{"@id":"https:\/\/vielhuber.de\/blog\/lamp-stack-mit-windows-wsl\/"},"wordCount":316,"publisher":{"@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef"},"articleSection":["Blog"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/vielhuber.de\/blog\/lamp-stack-mit-windows-wsl\/","url":"https:\/\/vielhuber.de\/blog\/lamp-stack-mit-windows-wsl\/","name":"LAMP-Stack im Windows Subsystem for Linux &#060; Vielhuber David","isPartOf":{"@id":"https:\/\/vielhuber.de\/#website"},"datePublished":"2018-11-27T15:20:28+00:00","dateModified":"2020-07-13T19:15:28+00:00","description":"Auf der Suche nach der optimalen Entwicklungsumgebung bieten sich unter Windows 10 neben Komplettl\u00f6sungen wie XAMPP, WAMP&nbsp;und MAMP, einer nativen","breadcrumb":{"@id":"https:\/\/vielhuber.de\/blog\/lamp-stack-mit-windows-wsl\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vielhuber.de\/blog\/lamp-stack-mit-windows-wsl\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/vielhuber.de\/blog\/lamp-stack-mit-windows-wsl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vielhuber.de\/"},{"@type":"ListItem","position":2,"name":"LAMP-Stack im Windows Subsystem for Linux"}]},{"@type":"WebSite","@id":"https:\/\/vielhuber.de\/#website","url":"https:\/\/vielhuber.de\/","name":"Vielhuber David","description":"Full-Stack Developer","publisher":{"@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vielhuber.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef","name":"David","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg","url":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg","contentUrl":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg","width":700,"height":552,"caption":"David"},"logo":{"@id":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg"},"sameAs":["https:\/\/x.com\/vielhuber"]}]}},"_links":{"self":[{"href":"https:\/\/vielhuber.de\/uk\/wp-json\/wp\/v2\/posts\/2068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vielhuber.de\/uk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vielhuber.de\/uk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vielhuber.de\/uk\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vielhuber.de\/uk\/wp-json\/wp\/v2\/comments?post=2068"}],"version-history":[{"count":15,"href":"https:\/\/vielhuber.de\/uk\/wp-json\/wp\/v2\/posts\/2068\/revisions"}],"predecessor-version":[{"id":2729,"href":"https:\/\/vielhuber.de\/uk\/wp-json\/wp\/v2\/posts\/2068\/revisions\/2729"}],"wp:attachment":[{"href":"https:\/\/vielhuber.de\/uk\/wp-json\/wp\/v2\/media?parent=2068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vielhuber.de\/uk\/wp-json\/wp\/v2\/categories?post=2068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vielhuber.de\/uk\/wp-json\/wp\/v2\/tags?post=2068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}