{"id":2383,"date":"2019-06-19T12:37:08","date_gmt":"2019-06-19T10:37:08","guid":{"rendered":"https:\/\/vielhuber.de\/?p=2383"},"modified":"2019-06-19T13:01:15","modified_gmt":"2019-06-19T11:01:15","slug":"quick-tip-google-tag-manager","status":"publish","type":"post","link":"https:\/\/vielhuber.de\/blog\/quick-tip-google-tag-manager\/","title":{"rendered":"Quick Tip: Google Tag Manager"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Der <a rel=\"noreferrer noopener\" aria-label=\"Google Tag Manager (opens in a new tab)\" href=\"https:\/\/www.google.com\/intl\/de\/tagmanager\/\" target=\"_blank\">Google Tag Manager<\/a> hat sich zum De-Facto-Standard f\u00fcr die Einbindung von Tracking-Scripten etabliert. Damit trennt man zum einen die Zust\u00e4ndigkeiten (Online-Marketing vs. Programmierung) sauber ab und kann zum anderen \u00fcber einen weiteren Deployment-Kanal schnell Trackings aufsetzen und modifizieren. Anbei folgen zwei kleine Tipps f\u00fcr das Aufsetzen von Triggern.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Bei der Erstellung von Triggern w\u00e4hlt man sehr h\u00e4ufig die Option \"\u00dcbereinstimmung mit CSS-Selektor\" als Ausl\u00f6sungsart aus. Tr\u00e4gt man beispielweise den Wert <strong>.foo .bar .button<\/strong> ein, so kommt es h\u00e4ufig vor, dass der Trigger nicht zuverl\u00e4ssig ausl\u00f6st. Der Grund daf\u00fcr ist meist, dass sich innerhalb des Button-Elements weitere HTML-Elemente (beispielsweise &lt;span>-Elemente f\u00fcr zus\u00e4tzliches Styling) verstecken k\u00f6nnen. Wenn man auf diese Kindelemente dann direkt klickt, l\u00f6st der Trigger nicht aus \u2013 das Event wird in der DOM-Hierarchie nicht nach oben propagiert (nicht gebubblet). Um das zu umgehen, wiederholt man den Selektor und f\u00fcgt den Universalselektor \"*\" an. Der gesamte Ausdruck lautet in unserem Beispiel  <strong>.foo .bar .button, .foo .bar .button *<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Als zweiten Tipp gibt es seit iOS 10.2 (bis zur aktuellen Version) ein st\u00f6rendes Verhalten im Safari-Browser: Trackt man mailto:-Links, erscheint unter bestimmten Umst\u00e4nden nach Tipp auf den Link folgende Meldung:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"401\" height=\"106\" src=\"https:\/\/vielhuber.de\/wp-content\/uploads\/safari-mailto-problem.png\" alt=\"\" class=\"wp-image-2384\"\/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Hier war der Triggertyp \"<strong>Klick - Nur Links<\/strong>\" mit der Option \"<strong>Auf Tags warten<\/strong>\" aktiviert. Dadurch verz\u00f6gert sich die Ansteuerung des eigentlichen Linkziels, was zur besagten Meldung f\u00fchrt. Nach dem Deaktivieren der Option tritt das Problem nicht mehr auf. Alternativ kann man auch den Triggertyp \"<strong>Klick - Alle Elemente<\/strong>\" verwenden und \u00fcber den CSS-Selektor das Ziel m\u00f6glichst genau als Link spezifizieren.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Google Tag Manager hat sich zum De-Facto-Standard f\u00fcr die Einbindung von Tracking-Scripten etabliert. Damit trennt man zum einen die Zust\u00e4ndigkeiten (Online-Marketing vs. Programmierung) sauber ab und kann zum anderen \u00fcber einen weiteren Deployment-Kanal schnell Trackings aufsetzen und modifizieren. Anbei folgen zwei kleine Tipps f\u00fcr das Aufsetzen von Triggern.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"gtbabel_prevent_lngs":"","gtbabel_alt_lng":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-2383","post","type-post","status-publish","format-standard","category-blog"],"acf":[],"yoast_head":"<title>Quick Tip: Google Tag Manager &#060; Vielhuber David<\/title>\n<meta name=\"description\" content=\"Der Google Tag Manager hat sich zum De-Facto-Standard f\u00fcr die Einbindung von Tracking-Scripten etabliert. Damit trennt man zum einen die Zust\u00e4ndigke...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vielhuber.de\/blog\/quick-tip-google-tag-manager\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quick Tip: Google Tag Manager &#060; Vielhuber David\" \/>\n<meta property=\"og:description\" content=\"Der Google Tag Manager hat sich zum De-Facto-Standard f\u00fcr die Einbindung von Tracking-Scripten etabliert. Damit trennt man zum einen die Zust\u00e4ndigkeiten\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vielhuber.de\/blog\/quick-tip-google-tag-manager\/\" \/>\n<meta property=\"og:site_name\" content=\"Vielhuber David\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-19T10:37:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-19T11:01:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vielhuber.de\/wp-content\/uploads\/safari-mailto-problem.png\" \/>\n<meta name=\"author\" content=\"David\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@vielhuber\" \/>\n<meta name=\"twitter:site\" content=\"@vielhuber\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"David\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/quick-tip-google-tag-manager\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/quick-tip-google-tag-manager\\\/\"},\"author\":{\"name\":\"David\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\"},\"headline\":\"Quick Tip: Google Tag Manager\",\"datePublished\":\"2019-06-19T10:37:08+00:00\",\"dateModified\":\"2019-06-19T11:01:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/quick-tip-google-tag-manager\\\/\"},\"wordCount\":276,\"publisher\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\"},\"image\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/quick-tip-google-tag-manager\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/safari-mailto-problem.png\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/quick-tip-google-tag-manager\\\/\",\"url\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/quick-tip-google-tag-manager\\\/\",\"name\":\"Quick Tip: Google Tag Manager &#060; Vielhuber David\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/quick-tip-google-tag-manager\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/quick-tip-google-tag-manager\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/safari-mailto-problem.png\",\"datePublished\":\"2019-06-19T10:37:08+00:00\",\"dateModified\":\"2019-06-19T11:01:15+00:00\",\"description\":\"Der Google Tag Manager hat sich zum De-Facto-Standard f\u00fcr die Einbindung von Tracking-Scripten etabliert. Damit trennt man zum einen die Zust\u00e4ndigkeiten\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/quick-tip-google-tag-manager\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vielhuber.de\\\/blog\\\/quick-tip-google-tag-manager\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/quick-tip-google-tag-manager\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/safari-mailto-problem.png\",\"contentUrl\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/safari-mailto-problem.png\",\"width\":401,\"height\":106},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/quick-tip-google-tag-manager\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vielhuber.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quick Tip: Google Tag Manager\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#website\",\"url\":\"https:\\\/\\\/vielhuber.de\\\/\",\"name\":\"Vielhuber David\",\"description\":\"Full-Stack Developer\",\"publisher\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vielhuber.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\",\"name\":\"David\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\",\"url\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\",\"contentUrl\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\",\"width\":700,\"height\":552,\"caption\":\"David\"},\"logo\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/vielhuber\"]}]}<\/script>","yoast_head_json":{"title":"Quick Tip: Google Tag Manager &#060; Vielhuber David","description":"Der Google Tag Manager hat sich zum De-Facto-Standard f\u00fcr die Einbindung von Tracking-Scripten etabliert. Damit trennt man zum einen die Zust\u00e4ndigke...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vielhuber.de\/blog\/quick-tip-google-tag-manager\/","og_locale":"de_DE","og_type":"article","og_title":"Quick Tip: Google Tag Manager &#060; Vielhuber David","og_description":"Der Google Tag Manager hat sich zum De-Facto-Standard f\u00fcr die Einbindung von Tracking-Scripten etabliert. Damit trennt man zum einen die Zust\u00e4ndigkeiten","og_url":"https:\/\/vielhuber.de\/blog\/quick-tip-google-tag-manager\/","og_site_name":"Vielhuber David","article_published_time":"2019-06-19T10:37:08+00:00","article_modified_time":"2019-06-19T11:01:15+00:00","og_image":[{"url":"https:\/\/vielhuber.de\/wp-content\/uploads\/safari-mailto-problem.png","type":"","width":"","height":""}],"author":"David","twitter_card":"summary_large_image","twitter_creator":"@vielhuber","twitter_site":"@vielhuber","twitter_misc":{"Verfasst von":"David","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vielhuber.de\/blog\/quick-tip-google-tag-manager\/#article","isPartOf":{"@id":"https:\/\/vielhuber.de\/blog\/quick-tip-google-tag-manager\/"},"author":{"name":"David","@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef"},"headline":"Quick Tip: Google Tag Manager","datePublished":"2019-06-19T10:37:08+00:00","dateModified":"2019-06-19T11:01:15+00:00","mainEntityOfPage":{"@id":"https:\/\/vielhuber.de\/blog\/quick-tip-google-tag-manager\/"},"wordCount":276,"publisher":{"@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef"},"image":{"@id":"https:\/\/vielhuber.de\/blog\/quick-tip-google-tag-manager\/#primaryimage"},"thumbnailUrl":"https:\/\/vielhuber.de\/wp-content\/uploads\/safari-mailto-problem.png","articleSection":["Blog"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/vielhuber.de\/blog\/quick-tip-google-tag-manager\/","url":"https:\/\/vielhuber.de\/blog\/quick-tip-google-tag-manager\/","name":"Quick Tip: Google Tag Manager &#060; Vielhuber David","isPartOf":{"@id":"https:\/\/vielhuber.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vielhuber.de\/blog\/quick-tip-google-tag-manager\/#primaryimage"},"image":{"@id":"https:\/\/vielhuber.de\/blog\/quick-tip-google-tag-manager\/#primaryimage"},"thumbnailUrl":"https:\/\/vielhuber.de\/wp-content\/uploads\/safari-mailto-problem.png","datePublished":"2019-06-19T10:37:08+00:00","dateModified":"2019-06-19T11:01:15+00:00","description":"Der Google Tag Manager hat sich zum De-Facto-Standard f\u00fcr die Einbindung von Tracking-Scripten etabliert. Damit trennt man zum einen die Zust\u00e4ndigkeiten","breadcrumb":{"@id":"https:\/\/vielhuber.de\/blog\/quick-tip-google-tag-manager\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vielhuber.de\/blog\/quick-tip-google-tag-manager\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/vielhuber.de\/blog\/quick-tip-google-tag-manager\/#primaryimage","url":"https:\/\/vielhuber.de\/wp-content\/uploads\/safari-mailto-problem.png","contentUrl":"https:\/\/vielhuber.de\/wp-content\/uploads\/safari-mailto-problem.png","width":401,"height":106},{"@type":"BreadcrumbList","@id":"https:\/\/vielhuber.de\/blog\/quick-tip-google-tag-manager\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vielhuber.de\/"},{"@type":"ListItem","position":2,"name":"Quick Tip: Google Tag Manager"}]},{"@type":"WebSite","@id":"https:\/\/vielhuber.de\/#website","url":"https:\/\/vielhuber.de\/","name":"Vielhuber David","description":"Full-Stack Developer","publisher":{"@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vielhuber.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef","name":"David","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg","url":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg","contentUrl":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg","width":700,"height":552,"caption":"David"},"logo":{"@id":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg"},"sameAs":["https:\/\/x.com\/vielhuber"]}]}},"_links":{"self":[{"href":"https:\/\/vielhuber.de\/tr\/wp-json\/wp\/v2\/posts\/2383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vielhuber.de\/tr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vielhuber.de\/tr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vielhuber.de\/tr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vielhuber.de\/tr\/wp-json\/wp\/v2\/comments?post=2383"}],"version-history":[{"count":9,"href":"https:\/\/vielhuber.de\/tr\/wp-json\/wp\/v2\/posts\/2383\/revisions"}],"predecessor-version":[{"id":2393,"href":"https:\/\/vielhuber.de\/tr\/wp-json\/wp\/v2\/posts\/2383\/revisions\/2393"}],"wp:attachment":[{"href":"https:\/\/vielhuber.de\/tr\/wp-json\/wp\/v2\/media?parent=2383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vielhuber.de\/tr\/wp-json\/wp\/v2\/categories?post=2383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vielhuber.de\/tr\/wp-json\/wp\/v2\/tags?post=2383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}