{"id":974,"date":"2015-03-22T23:37:31","date_gmt":"2015-03-22T22:37:31","guid":{"rendered":"https:\/\/vielhuber.de\/?p=974"},"modified":"2016-06-05T22:59:45","modified_gmt":"2016-06-05T20:59:45","slug":"doppelte-passwortabfrage-bei-ssl","status":"publish","type":"post","link":"https:\/\/vielhuber.de\/blog\/doppelte-passwortabfrage-bei-ssl\/","title":{"rendered":"Doppelte Passwortabfrage bei SSL"},"content":{"rendered":"<p>Bei folgender Konstellation kommt es stets zu einer unsch\u00f6nen Nebenwirkung:\u00a0Sch\u00fctzt man seine Seite mit htaccess\/htpasswd und erzwingt gleichzeitig eine SSL-Verbindung, so ben\u00f6tigt man stets zweimal dieselbe Passworteingabe (einmal f\u00fcr http und nach erfolgreicher Eingabe nochmals f\u00fcr https). Mit Hilfe von den in Apache 2.4 eingef\u00fchrten <a href=\"http:\/\/httpd.apache.org\/docs\/current\/sections.html\" target=\"_blank\">configuration sections<\/a>\u00a0l\u00e4sst sich das Problem einfach in den Griff bekommen.<\/p>\n<p><!--more--><\/p>\n<pre><code class=\"html\"># SSL erzwingen\r\nRewriteEngine On\r\nRewriteCond %{HTTPS} !=on\r\nRewriteRule ^ https:\/\/%{HTTP_HOST}%{REQUEST_URI} [L,R=301]\r\n\r\n# Authentifizierung (nur bei verschl\u00fcsselten Verbindungen)\r\n&lt;If \"%{HTTPS} == 'on'\"&gt;\r\nAuthUserFile \/path\/to\/.htpasswd\r\nAuthName \"Interner Bereich\"\r\nAuthType Basic\r\nrequire valid-user\r\n&lt;\/If&gt;<\/code><\/pre>\n","protected":false},"excerpt":{"rendered":"<p>Bei folgender Konstellation kommt es stets zu einer unsch\u00f6nen Nebenwirkung:\u00a0Sch\u00fctzt man seine Seite mit htaccess\/htpasswd und erzwingt gleichzeitig eine SSL-Verbindung, so ben\u00f6tigt man stets zweimal dieselbe Passworteingabe (einmal f\u00fcr http und nach erfolgreicher Eingabe nochmals f\u00fcr https). Mit Hilfe von den in Apache 2.4 eingef\u00fchrten configuration sections\u00a0l\u00e4sst sich das Problem einfach in den Griff bekommen.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"gtbabel_prevent_lngs":"","gtbabel_alt_lng":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-974","post","type-post","status-publish","format-standard","category-blog"],"acf":[],"yoast_head":"<title>Doppelte Passwortabfrage bei SSL &#060; Vielhuber David<\/title>\n<meta name=\"description\" content=\"Bei folgender Konstellation kommt es stets zu einer unsch\u00f6nen Nebenwirkung:\u00a0Sch\u00fctzt man seine Seite mit htaccess\/htpasswd und erzwingt gleichzeitig...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vielhuber.de\/blog\/doppelte-passwortabfrage-bei-ssl\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Doppelte Passwortabfrage bei SSL &#060; Vielhuber David\" \/>\n<meta property=\"og:description\" content=\"Bei folgender Konstellation kommt es stets zu einer unsch\u00f6nen Nebenwirkung:\u00a0Sch\u00fctzt man seine Seite mit htaccess\/htpasswd und erzwingt gleichzeitig eine\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vielhuber.de\/blog\/doppelte-passwortabfrage-bei-ssl\/\" \/>\n<meta property=\"og:site_name\" content=\"Vielhuber David\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-22T22:37:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-06-05T20:59:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"552\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@vielhuber\" \/>\n<meta name=\"twitter:site\" content=\"@vielhuber\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"David\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/doppelte-passwortabfrage-bei-ssl\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/doppelte-passwortabfrage-bei-ssl\\\/\"},\"author\":{\"name\":\"David\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\"},\"headline\":\"Doppelte Passwortabfrage bei SSL\",\"datePublished\":\"2015-03-22T22:37:31+00:00\",\"dateModified\":\"2016-06-05T20:59:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/doppelte-passwortabfrage-bei-ssl\\\/\"},\"wordCount\":68,\"publisher\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\"},\"articleSection\":[\"Blog\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/doppelte-passwortabfrage-bei-ssl\\\/\",\"url\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/doppelte-passwortabfrage-bei-ssl\\\/\",\"name\":\"Doppelte Passwortabfrage bei SSL &#060; Vielhuber David\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#website\"},\"datePublished\":\"2015-03-22T22:37:31+00:00\",\"dateModified\":\"2016-06-05T20:59:45+00:00\",\"description\":\"Bei folgender Konstellation kommt es stets zu einer unsch\u00f6nen Nebenwirkung:\u00a0Sch\u00fctzt man seine Seite mit htaccess\\\/htpasswd und erzwingt gleichzeitig eine\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/doppelte-passwortabfrage-bei-ssl\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vielhuber.de\\\/blog\\\/doppelte-passwortabfrage-bei-ssl\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/doppelte-passwortabfrage-bei-ssl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vielhuber.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Doppelte Passwortabfrage bei SSL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#website\",\"url\":\"https:\\\/\\\/vielhuber.de\\\/\",\"name\":\"Vielhuber David\",\"description\":\"Full-Stack Developer\",\"publisher\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vielhuber.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\",\"name\":\"David\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\",\"url\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\",\"contentUrl\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\",\"width\":700,\"height\":552,\"caption\":\"David\"},\"logo\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/vielhuber\"]}]}<\/script>","yoast_head_json":{"title":"Doppelte Passwortabfrage bei SSL &#060; Vielhuber David","description":"Bei folgender Konstellation kommt es stets zu einer unsch\u00f6nen Nebenwirkung:\u00a0Sch\u00fctzt man seine Seite mit htaccess\/htpasswd und erzwingt gleichzeitig...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vielhuber.de\/blog\/doppelte-passwortabfrage-bei-ssl\/","og_locale":"de_DE","og_type":"article","og_title":"Doppelte Passwortabfrage bei SSL &#060; Vielhuber David","og_description":"Bei folgender Konstellation kommt es stets zu einer unsch\u00f6nen Nebenwirkung:\u00a0Sch\u00fctzt man seine Seite mit htaccess\/htpasswd und erzwingt gleichzeitig eine","og_url":"https:\/\/vielhuber.de\/blog\/doppelte-passwortabfrage-bei-ssl\/","og_site_name":"Vielhuber David","article_published_time":"2015-03-22T22:37:31+00:00","article_modified_time":"2016-06-05T20:59:45+00:00","og_image":[{"width":700,"height":552,"url":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg","type":"image\/jpeg"}],"author":"David","twitter_card":"summary_large_image","twitter_creator":"@vielhuber","twitter_site":"@vielhuber","twitter_misc":{"Verfasst von":"David","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vielhuber.de\/blog\/doppelte-passwortabfrage-bei-ssl\/#article","isPartOf":{"@id":"https:\/\/vielhuber.de\/blog\/doppelte-passwortabfrage-bei-ssl\/"},"author":{"name":"David","@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef"},"headline":"Doppelte Passwortabfrage bei SSL","datePublished":"2015-03-22T22:37:31+00:00","dateModified":"2016-06-05T20:59:45+00:00","mainEntityOfPage":{"@id":"https:\/\/vielhuber.de\/blog\/doppelte-passwortabfrage-bei-ssl\/"},"wordCount":68,"publisher":{"@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef"},"articleSection":["Blog"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/vielhuber.de\/blog\/doppelte-passwortabfrage-bei-ssl\/","url":"https:\/\/vielhuber.de\/blog\/doppelte-passwortabfrage-bei-ssl\/","name":"Doppelte Passwortabfrage bei SSL &#060; Vielhuber David","isPartOf":{"@id":"https:\/\/vielhuber.de\/#website"},"datePublished":"2015-03-22T22:37:31+00:00","dateModified":"2016-06-05T20:59:45+00:00","description":"Bei folgender Konstellation kommt es stets zu einer unsch\u00f6nen Nebenwirkung:\u00a0Sch\u00fctzt man seine Seite mit htaccess\/htpasswd und erzwingt gleichzeitig eine","breadcrumb":{"@id":"https:\/\/vielhuber.de\/blog\/doppelte-passwortabfrage-bei-ssl\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vielhuber.de\/blog\/doppelte-passwortabfrage-bei-ssl\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/vielhuber.de\/blog\/doppelte-passwortabfrage-bei-ssl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vielhuber.de\/"},{"@type":"ListItem","position":2,"name":"Doppelte Passwortabfrage bei SSL"}]},{"@type":"WebSite","@id":"https:\/\/vielhuber.de\/#website","url":"https:\/\/vielhuber.de\/","name":"Vielhuber David","description":"Full-Stack Developer","publisher":{"@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vielhuber.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef","name":"David","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg","url":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg","contentUrl":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg","width":700,"height":552,"caption":"David"},"logo":{"@id":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg"},"sameAs":["https:\/\/x.com\/vielhuber"]}]}},"_links":{"self":[{"href":"https:\/\/vielhuber.de\/eo\/wp-json\/wp\/v2\/posts\/974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vielhuber.de\/eo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vielhuber.de\/eo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vielhuber.de\/eo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vielhuber.de\/eo\/wp-json\/wp\/v2\/comments?post=974"}],"version-history":[{"count":1,"href":"https:\/\/vielhuber.de\/eo\/wp-json\/wp\/v2\/posts\/974\/revisions"}],"predecessor-version":[{"id":1297,"href":"https:\/\/vielhuber.de\/eo\/wp-json\/wp\/v2\/posts\/974\/revisions\/1297"}],"wp:attachment":[{"href":"https:\/\/vielhuber.de\/eo\/wp-json\/wp\/v2\/media?parent=974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vielhuber.de\/eo\/wp-json\/wp\/v2\/categories?post=974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vielhuber.de\/eo\/wp-json\/wp\/v2\/tags?post=974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}