{"id":2893,"date":"2021-02-11T02:58:09","date_gmt":"2021-02-11T01:58:09","guid":{"rendered":"https:\/\/vielhuber.de\/?p=2893"},"modified":"2021-02-11T03:06:27","modified_gmt":"2021-02-11T02:06:27","slug":"wordpress-suche-erweitern","status":"publish","type":"post","link":"https:\/\/vielhuber.de\/blog\/wordpress-suche-erweitern\/","title":{"rendered":"WordPress Suche erweitern"},"content":{"rendered":"\n<p>Will man die native WordPress-Suche um beispielsweise Meta-Felder erweitern, empfiehlt sich ein Blick in die gefeuerten <a href=\"https:\/\/core.trac.wordpress.org\/browser\/tags\/5.6\/src\/wp-includes\/class-wp-query.php\" target=\"_blank\" rel=\"noreferrer noopener\">Filter<\/a>. Damit die Paginierung weiterhin funktioniert und man auch zuk\u00fcnftige Verbesserungen in der Suche nicht aushebelt, empfiehlt sich der Hook <a href=\"https:\/\/developer.wordpress.org\/reference\/hooks\/posts_search\/\" target=\"_blank\" rel=\"noreferrer noopener\">posts_search<\/a>. Folgender Code erweitert unter zu Hilfenahme der Funktionen <a href=\"https:\/\/dev.mysql.com\/doc\/refman\/8.0\/en\/regexp.html\" target=\"_blank\" rel=\"noreferrer noopener\">REGEXP<\/a> und <a href=\"https:\/\/dev.mysql.com\/doc\/refman\/8.0\/en\/xml-functions.html\" target=\"_blank\" rel=\"noreferrer noopener\">ExtractValue<\/a> diese Suche um Posts, die in allen Meta-Feldern einen der eingegebenen Suchw\u00f6rter beinhaltet.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"githubgist\" data-gist-file=\"functions.php\">04dab4ed835deeafde5ce44275163864<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Will man die native WordPress-Suche um beispielsweise Meta-Felder erweitern, empfiehlt sich ein Blick in die gefeuerten Filter. Damit die Paginierung weiterhin funktioniert und man auch zuk\u00fcnftige Verbesserungen in der Suche nicht aushebelt, empfiehlt sich der Hook posts_search. Folgender Code erweitert unter zu Hilfenahme der Funktionen REGEXP und ExtractValue diese Suche um Posts, die in allen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"gtbabel_prevent_lngs":"","gtbabel_alt_lng":"","footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-2893","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-blog"},"acf":[],"yoast_head":"<title>WordPress Suche erweitern &#060; Vielhuber David<\/title>\n<meta name=\"description\" content=\"Will man die native WordPress-Suche um beispielsweise Meta-Felder erweitern, empfiehlt sich ein Blick in die gefeuerten Filter. Damit die Paginierung\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vielhuber.de\/blog\/wordpress-suche-erweitern\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WordPress Suche erweitern &#060; Vielhuber David\" \/>\n<meta property=\"og:description\" content=\"Will man die native WordPress-Suche um beispielsweise Meta-Felder erweitern, empfiehlt sich ein Blick in die gefeuerten Filter. Damit die Paginierung\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vielhuber.de\/blog\/wordpress-suche-erweitern\/\" \/>\n<meta property=\"og:site_name\" content=\"Vielhuber David\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-11T01:58:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-11T02:06:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"552\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@vielhuber\" \/>\n<meta name=\"twitter:site\" content=\"@vielhuber\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"David\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/wordpress-suche-erweitern\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/wordpress-suche-erweitern\\\/\"},\"author\":{\"name\":\"David\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\"},\"headline\":\"WordPress Suche erweitern\",\"datePublished\":\"2021-02-11T01:58:09+00:00\",\"dateModified\":\"2021-02-11T02:06:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/wordpress-suche-erweitern\\\/\"},\"wordCount\":71,\"publisher\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\"},\"articleSection\":[\"Blog\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/wordpress-suche-erweitern\\\/\",\"url\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/wordpress-suche-erweitern\\\/\",\"name\":\"WordPress Suche erweitern &#060; Vielhuber David\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#website\"},\"datePublished\":\"2021-02-11T01:58:09+00:00\",\"dateModified\":\"2021-02-11T02:06:27+00:00\",\"description\":\"Will man die native WordPress-Suche um beispielsweise Meta-Felder erweitern, empfiehlt sich ein Blick in die gefeuerten Filter. Damit die Paginierung\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/wordpress-suche-erweitern\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vielhuber.de\\\/blog\\\/wordpress-suche-erweitern\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/wordpress-suche-erweitern\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vielhuber.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WordPress Suche erweitern\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#website\",\"url\":\"https:\\\/\\\/vielhuber.de\\\/\",\"name\":\"Vielhuber David\",\"description\":\"Full-Stack Developer\",\"publisher\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vielhuber.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\",\"name\":\"David\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\",\"url\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\",\"contentUrl\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\",\"width\":700,\"height\":552,\"caption\":\"David\"},\"logo\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/vielhuber\"]}]}<\/script>","yoast_head_json":{"title":"WordPress Suche erweitern &#060; Vielhuber David","description":"Will man die native WordPress-Suche um beispielsweise Meta-Felder erweitern, empfiehlt sich ein Blick in die gefeuerten Filter. Damit die Paginierung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vielhuber.de\/blog\/wordpress-suche-erweitern\/","og_locale":"de_DE","og_type":"article","og_title":"WordPress Suche erweitern &#060; Vielhuber David","og_description":"Will man die native WordPress-Suche um beispielsweise Meta-Felder erweitern, empfiehlt sich ein Blick in die gefeuerten Filter. Damit die Paginierung","og_url":"https:\/\/vielhuber.de\/blog\/wordpress-suche-erweitern\/","og_site_name":"Vielhuber David","article_published_time":"2021-02-11T01:58:09+00:00","article_modified_time":"2021-02-11T02:06:27+00:00","og_image":[{"width":700,"height":552,"url":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg","type":"image\/jpeg"}],"author":"David","twitter_card":"summary_large_image","twitter_creator":"@vielhuber","twitter_site":"@vielhuber","twitter_misc":{"Verfasst von":"David","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vielhuber.de\/blog\/wordpress-suche-erweitern\/#article","isPartOf":{"@id":"https:\/\/vielhuber.de\/blog\/wordpress-suche-erweitern\/"},"author":{"name":"David","@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef"},"headline":"WordPress Suche erweitern","datePublished":"2021-02-11T01:58:09+00:00","dateModified":"2021-02-11T02:06:27+00:00","mainEntityOfPage":{"@id":"https:\/\/vielhuber.de\/blog\/wordpress-suche-erweitern\/"},"wordCount":71,"publisher":{"@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef"},"articleSection":["Blog"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/vielhuber.de\/blog\/wordpress-suche-erweitern\/","url":"https:\/\/vielhuber.de\/blog\/wordpress-suche-erweitern\/","name":"WordPress Suche erweitern &#060; Vielhuber David","isPartOf":{"@id":"https:\/\/vielhuber.de\/#website"},"datePublished":"2021-02-11T01:58:09+00:00","dateModified":"2021-02-11T02:06:27+00:00","description":"Will man die native WordPress-Suche um beispielsweise Meta-Felder erweitern, empfiehlt sich ein Blick in die gefeuerten Filter. Damit die Paginierung","breadcrumb":{"@id":"https:\/\/vielhuber.de\/blog\/wordpress-suche-erweitern\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vielhuber.de\/blog\/wordpress-suche-erweitern\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/vielhuber.de\/blog\/wordpress-suche-erweitern\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vielhuber.de\/"},{"@type":"ListItem","position":2,"name":"WordPress Suche erweitern"}]},{"@type":"WebSite","@id":"https:\/\/vielhuber.de\/#website","url":"https:\/\/vielhuber.de\/","name":"Vielhuber David","description":"Full-Stack Developer","publisher":{"@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vielhuber.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef","name":"David","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg","url":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg","contentUrl":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg","width":700,"height":552,"caption":"David"},"logo":{"@id":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg"},"sameAs":["https:\/\/x.com\/vielhuber"]}]}},"_links":{"self":[{"href":"https:\/\/vielhuber.de\/el\/wp-json\/wp\/v2\/posts\/2893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vielhuber.de\/el\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vielhuber.de\/el\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vielhuber.de\/el\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vielhuber.de\/el\/wp-json\/wp\/v2\/comments?post=2893"}],"version-history":[{"count":6,"href":"https:\/\/vielhuber.de\/el\/wp-json\/wp\/v2\/posts\/2893\/revisions"}],"predecessor-version":[{"id":2901,"href":"https:\/\/vielhuber.de\/el\/wp-json\/wp\/v2\/posts\/2893\/revisions\/2901"}],"wp:attachment":[{"href":"https:\/\/vielhuber.de\/el\/wp-json\/wp\/v2\/media?parent=2893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vielhuber.de\/el\/wp-json\/wp\/v2\/categories?post=2893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vielhuber.de\/el\/wp-json\/wp\/v2\/tags?post=2893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}