{"id":2255,"date":"2019-04-28T00:32:09","date_gmt":"2019-04-27T22:32:09","guid":{"rendered":"https:\/\/vielhuber.de\/?p=2255"},"modified":"2019-04-28T00:37:42","modified_gmt":"2019-04-27T22:37:42","slug":"leserechte-in-google-sheets","status":"publish","type":"post","link":"https:\/\/vielhuber.de\/blog\/leserechte-in-google-sheets\/","title":{"rendered":"Leserechte in Google Sheets"},"content":{"rendered":"\n<p>Bei der Arbeit mit <a href=\"https:\/\/support.google.com\/docs\/answer\/1218656?co=GENIE.Platform%3DDesktop&amp;hl=en\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (\u00f6ffnet in neuem Tab)\">Google Sheets<\/a> lassen sich innerhalb eines Spreadsheets feine, userbasierte Regeln f\u00fcr das Editieren von Tabellenbl\u00e4ttern, Spalten und Zeilen festlegen. Leider gibt es keine M\u00f6glichkeit, Leserechte einzuschr\u00e4nken. Dies w\u00e4re jedoch in vielen Szenarien sehr hilfreich. So zeigt man seinen Kunden nur diejenigen Tickets, die ihn betreffen oder dem Mitarbeiter nur die Projekte, an denen er arbeitet.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Eine m\u00f6gliche L\u00f6sung besteht darin, ein sog. Mastersheet anzulegen und mit Hilfe von <a rel=\"noreferrer noopener\" aria-label=\"IMPORTRANGE  (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/support.google.com\/docs\/answer\/3093340?hl=de\" target=\"_blank\">IMPORTRANGE<\/a> ausgew\u00e4hlte Daten von dort aus in eine Richtung lesend anzuzapfen. Leider bedeutet das sehr viel Handarbeit: Neue Sheets anlegen, Dateirechte vergeben, IMPORTRANGE-Formel erarbeiten und einbauen, Permission akzeptieren, Formatierungen setzen. \u00c4ndert sich die Struktur oder das Format, muss das dann bei allen Spreadsheets einzeln manuell von Hand erledigt werden.<\/p>\n\n\n\n<p>Folgendes <a rel=\"noreferrer noopener\" href=\"https:\/\/developers.google.com\/apps-script\/\" target=\"_blank\">Google Apps Script<\/a> erledigt das automatisch. F\u00fchrt man die Methode <strong>init()<\/strong> im Mastersheet einmal aus, werden jeweils alle Slavesheets automatisch angelegt, Rechte vergeben sowie Formeln und Formatierungen gesetzt. \u00c4ndern sich Daten im Mastersheet, werden diese automatisch im Slavesheet gespiegelt. \u00c4ndert sich die Struktur des Mastersheets, f\u00fchrt man <strong>init()<\/strong> einfach erneut aus (vorherige Sheets werden dabei automatisch aktualisiert).<\/p>\n\n\n\n<p class=\"githubgist\" data-gist-file=\"script.js\">82ba709df04366e65cb3a42f84f19631<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bei der Arbeit mit Google Sheets lassen sich innerhalb eines Spreadsheets feine, userbasierte Regeln f\u00fcr das Editieren von Tabellenbl\u00e4ttern, Spalten und Zeilen festlegen. Leider gibt es keine M\u00f6glichkeit, Leserechte einzuschr\u00e4nken. Dies w\u00e4re jedoch in vielen Szenarien sehr hilfreich. So zeigt man seinen Kunden nur diejenigen Tickets, die ihn betreffen oder dem Mitarbeiter nur die Projekte, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"gtbabel_prevent_lngs":"","gtbabel_alt_lng":"","footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-2255","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-blog"},"acf":[],"yoast_head":"<title>Leserechte in Google Sheets &#060; Vielhuber David<\/title>\n<meta name=\"description\" content=\"Bei der Arbeit mit Google Sheets lassen sich innerhalb eines Spreadsheets feine, userbasierte Regeln f\u00fcr das Editieren von Tabellenbl\u00e4ttern, Spalten...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vielhuber.de\/blog\/leserechte-in-google-sheets\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Leserechte in Google Sheets &#060; Vielhuber David\" \/>\n<meta property=\"og:description\" content=\"Bei der Arbeit mit Google Sheets lassen sich innerhalb eines Spreadsheets feine, userbasierte Regeln f\u00fcr das Editieren von Tabellenbl\u00e4ttern, Spalten und\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vielhuber.de\/blog\/leserechte-in-google-sheets\/\" \/>\n<meta property=\"og:site_name\" content=\"Vielhuber David\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-27T22:32:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-27T22:37:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"552\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@vielhuber\" \/>\n<meta name=\"twitter:site\" content=\"@vielhuber\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"David\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/leserechte-in-google-sheets\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/leserechte-in-google-sheets\\\/\"},\"author\":{\"name\":\"David\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\"},\"headline\":\"Leserechte in Google Sheets\",\"datePublished\":\"2019-04-27T22:32:09+00:00\",\"dateModified\":\"2019-04-27T22:37:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/leserechte-in-google-sheets\\\/\"},\"wordCount\":200,\"publisher\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\"},\"articleSection\":[\"Blog\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/leserechte-in-google-sheets\\\/\",\"url\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/leserechte-in-google-sheets\\\/\",\"name\":\"Leserechte in Google Sheets &#060; Vielhuber David\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#website\"},\"datePublished\":\"2019-04-27T22:32:09+00:00\",\"dateModified\":\"2019-04-27T22:37:42+00:00\",\"description\":\"Bei der Arbeit mit Google Sheets lassen sich innerhalb eines Spreadsheets feine, userbasierte Regeln f\u00fcr das Editieren von Tabellenbl\u00e4ttern, Spalten und\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/leserechte-in-google-sheets\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vielhuber.de\\\/blog\\\/leserechte-in-google-sheets\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/leserechte-in-google-sheets\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vielhuber.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Leserechte in Google Sheets\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#website\",\"url\":\"https:\\\/\\\/vielhuber.de\\\/\",\"name\":\"Vielhuber David\",\"description\":\"Full-Stack Developer\",\"publisher\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vielhuber.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\",\"name\":\"David\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\",\"url\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\",\"contentUrl\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\",\"width\":700,\"height\":552,\"caption\":\"David\"},\"logo\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/vielhuber\"]}]}<\/script>","yoast_head_json":{"title":"Leserechte in Google Sheets &#060; Vielhuber David","description":"Bei der Arbeit mit Google Sheets lassen sich innerhalb eines Spreadsheets feine, userbasierte Regeln f\u00fcr das Editieren von Tabellenbl\u00e4ttern, Spalten...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vielhuber.de\/blog\/leserechte-in-google-sheets\/","og_locale":"de_DE","og_type":"article","og_title":"Leserechte in Google Sheets &#060; Vielhuber David","og_description":"Bei der Arbeit mit Google Sheets lassen sich innerhalb eines Spreadsheets feine, userbasierte Regeln f\u00fcr das Editieren von Tabellenbl\u00e4ttern, Spalten und","og_url":"https:\/\/vielhuber.de\/blog\/leserechte-in-google-sheets\/","og_site_name":"Vielhuber David","article_published_time":"2019-04-27T22:32:09+00:00","article_modified_time":"2019-04-27T22:37:42+00:00","og_image":[{"width":700,"height":552,"url":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg","type":"image\/jpeg"}],"author":"David","twitter_card":"summary_large_image","twitter_creator":"@vielhuber","twitter_site":"@vielhuber","twitter_misc":{"Verfasst von":"David","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vielhuber.de\/blog\/leserechte-in-google-sheets\/#article","isPartOf":{"@id":"https:\/\/vielhuber.de\/blog\/leserechte-in-google-sheets\/"},"author":{"name":"David","@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef"},"headline":"Leserechte in Google Sheets","datePublished":"2019-04-27T22:32:09+00:00","dateModified":"2019-04-27T22:37:42+00:00","mainEntityOfPage":{"@id":"https:\/\/vielhuber.de\/blog\/leserechte-in-google-sheets\/"},"wordCount":200,"publisher":{"@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef"},"articleSection":["Blog"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/vielhuber.de\/blog\/leserechte-in-google-sheets\/","url":"https:\/\/vielhuber.de\/blog\/leserechte-in-google-sheets\/","name":"Leserechte in Google Sheets &#060; Vielhuber David","isPartOf":{"@id":"https:\/\/vielhuber.de\/#website"},"datePublished":"2019-04-27T22:32:09+00:00","dateModified":"2019-04-27T22:37:42+00:00","description":"Bei der Arbeit mit Google Sheets lassen sich innerhalb eines Spreadsheets feine, userbasierte Regeln f\u00fcr das Editieren von Tabellenbl\u00e4ttern, Spalten und","breadcrumb":{"@id":"https:\/\/vielhuber.de\/blog\/leserechte-in-google-sheets\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vielhuber.de\/blog\/leserechte-in-google-sheets\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/vielhuber.de\/blog\/leserechte-in-google-sheets\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vielhuber.de\/"},{"@type":"ListItem","position":2,"name":"Leserechte in Google Sheets"}]},{"@type":"WebSite","@id":"https:\/\/vielhuber.de\/#website","url":"https:\/\/vielhuber.de\/","name":"Vielhuber David","description":"Full-Stack Developer","publisher":{"@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vielhuber.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef","name":"David","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg","url":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg","contentUrl":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg","width":700,"height":552,"caption":"David"},"logo":{"@id":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg"},"sameAs":["https:\/\/x.com\/vielhuber"]}]}},"_links":{"self":[{"href":"https:\/\/vielhuber.de\/da\/wp-json\/wp\/v2\/posts\/2255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vielhuber.de\/da\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vielhuber.de\/da\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vielhuber.de\/da\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vielhuber.de\/da\/wp-json\/wp\/v2\/comments?post=2255"}],"version-history":[{"count":8,"href":"https:\/\/vielhuber.de\/da\/wp-json\/wp\/v2\/posts\/2255\/revisions"}],"predecessor-version":[{"id":2263,"href":"https:\/\/vielhuber.de\/da\/wp-json\/wp\/v2\/posts\/2255\/revisions\/2263"}],"wp:attachment":[{"href":"https:\/\/vielhuber.de\/da\/wp-json\/wp\/v2\/media?parent=2255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vielhuber.de\/da\/wp-json\/wp\/v2\/categories?post=2255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vielhuber.de\/da\/wp-json\/wp\/v2\/tags?post=2255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}