{"id":1590,"date":"2017-06-13T22:08:43","date_gmt":"2017-06-13T20:08:43","guid":{"rendered":"https:\/\/vielhuber.de\/?p=1590"},"modified":"2017-06-24T12:28:05","modified_gmt":"2017-06-24T10:28:05","slug":"ssl-zertifikat-von-domainfactory-auf-iis-einbinden","status":"publish","type":"post","link":"https:\/\/vielhuber.de\/blog\/ssl-zertifikat-von-domainfactory-auf-iis-einbinden\/","title":{"rendered":"SSL-Zertifikat von DomainFactory auf IIS einbinden"},"content":{"rendered":"<p>In Zeiten von <a href=\"https:\/\/letsencrypt.org\/\" target=\"_blank\" rel=\"noopener\">Let's Encrypt<\/a> gelten verschl\u00fcsselte Websites inzwischen zum Standard. Doch auch Wildcard- oder Extended-Zertifikate mit besonders vertrauensw\u00fcrdiger Inhaber-Validierung werden oft ben\u00f6tigt. Der Anbieter <a href=\"https:\/\/www.df.eu\/de\/ssl-zertifikate\/\" target=\"_blank\" rel=\"noopener\">DomainFactory<\/a> bietet hier kosteng\u00fcnstige SSL-Zertifikate an, die man auch extern nutzen kann. Die Einrichtung auf einem aktuellen <a href=\"https:\/\/de.wikipedia.org\/wiki\/Microsoft_Internet_Information_Services\" target=\"_blank\" rel=\"noopener\">IIS<\/a>\u00a0gelingt ohne <a href=\"https:\/\/de.wikipedia.org\/wiki\/Certificate_Signing_Request\" target=\"_blank\" rel=\"noopener\">CSR<\/a>\u00a0mit Hilfe von <a href=\"https:\/\/www.openssl.org\/\" target=\"_blank\" rel=\"noopener\">OpenSSL<\/a>. Nachfolgend zeige ich kurz, welche Schritte dazu erforderlich sind.<\/p>\n<p><!--more--><\/p>\n<p>Zun\u00e4chst w\u00e4hlt man als Domainname die gew\u00fcnschte Adresse (durch Eingabe mit\u00a0\u201ewww\u201c, damit sp\u00e4ter sowohl https:\/\/tld.com als auch https:\/\/www.tld.com verschl\u00fcsselt sind):<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/vielhuber.de\/wp-content\/uploads\/935.png\" alt=\"SSL-Zertifikat IIS\" \/><\/p>\n<p>Nach der Auswahl des gew\u00fcnschten Zertifikats und der Laufzeit l\u00e4sst man DomainFactory einen eigenen CSR erzeugen:<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/vielhuber.de\/wp-content\/uploads\/365.png\" alt=\"SSL-Zertifikat IIS\" \/><\/p>\n<p>Die zweite Option (Upload eines eigenen CSRs) ist nicht notwendig und umst\u00e4ndlich (der IIS bietet standardm\u00e4\u00dfig keine M\u00f6glichkeit, von DomainFactory ben\u00f6tigte SHA256 verschl\u00fcsselte Requests zu erzeugen). Nach der erfolgreichen Bestellung l\u00e4dt man sich das SSL-Zertifikat, den privaten Schl\u00fcssel sowie das Intermediate CA Bundle herunter:<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/vielhuber.de\/wp-content\/uploads\/326-1.png\" alt=\"SSL-Zertifikat IIS\" \/><\/p>\n<p>Nun kombiniert man (unter Vergabe eines sicheren Passworts) mit Hilfe von OpenSSL den Schl\u00fcssel sowie das Zertifikat in einer pfx-Datei:<\/p>\n<pre><code>openssl pkcs12 -export -out www.tld.com.pfx -inkey www.tld.com.key -in www.tld.com.crt<\/code><\/pre>\n<p>Schlie\u00dflich l\u00e4dt man das Zwischenzertifikat auf den Windows-Server:<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/vielhuber.de\/wp-content\/uploads\/277.png\" alt=\"SSL-Zertifikat IIS\" \/><\/p>\n<p>Anschlie\u00dfend folgt der Import der erzeugten pfx-Datei im IIS-Manager (im Bereich Serverzertifikate) unter Eingabe des zuvor vergebenen Passworts:<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/vielhuber.de\/wp-content\/uploads\/836.png\" alt=\"SSL-Zertifikat IIS\" \/><\/p>\n<p>Schlie\u00dflich passt man noch die Bindungen (jeweils ein Eintrag mit und ein Eintrag ohne www) an:<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/vielhuber.de\/wp-content\/uploads\/481.png\" alt=\"SSL-Zertifikat IIS\" \/><\/p>\n<p>Soll der Server nach au\u00dfen hin erreichbar sein, \u00f6ffnet man im Router \/ in der Firewall noch Port 443.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In Zeiten von Let's Encrypt gelten verschl\u00fcsselte Websites inzwischen zum Standard. Doch auch Wildcard- oder Extended-Zertifikate mit besonders vertrauensw\u00fcrdiger Inhaber-Validierung werden oft ben\u00f6tigt. Der Anbieter DomainFactory bietet hier kosteng\u00fcnstige SSL-Zertifikate an, die man auch extern nutzen kann. Die Einrichtung auf einem aktuellen IIS\u00a0gelingt ohne CSR\u00a0mit Hilfe von OpenSSL. Nachfolgend zeige ich kurz, welche Schritte dazu [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"gtbabel_prevent_lngs":"","gtbabel_alt_lng":"","footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-1590","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-blog"},"acf":[],"yoast_head":"<title>SSL-Zertifikat von DomainFactory auf IIS einbinden<\/title>\n<meta name=\"description\" content=\"In Zeiten von Let&#039;s Encrypt gelten verschl\u00fcsselte Websites inzwischen zum Standard. Doch auch Wildcard- oder Extended-Zertifikate mit besonders\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vielhuber.de\/blog\/ssl-zertifikat-von-domainfactory-auf-iis-einbinden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SSL-Zertifikat von DomainFactory auf IIS einbinden\" \/>\n<meta property=\"og:description\" content=\"In Zeiten von Let&#039;s Encrypt gelten verschl\u00fcsselte Websites inzwischen zum Standard. Doch auch Wildcard- oder Extended-Zertifikate mit besonders\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vielhuber.de\/blog\/ssl-zertifikat-von-domainfactory-auf-iis-einbinden\/\" \/>\n<meta property=\"og:site_name\" content=\"Vielhuber David\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-13T20:08:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-06-24T10:28:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vielhuber.de\/wp-content\/uploads\/935.png\" \/>\n<meta name=\"author\" content=\"David\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@vielhuber\" \/>\n<meta name=\"twitter:site\" content=\"@vielhuber\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"David\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/ssl-zertifikat-von-domainfactory-auf-iis-einbinden\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/ssl-zertifikat-von-domainfactory-auf-iis-einbinden\\\/\"},\"author\":{\"name\":\"David\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\"},\"headline\":\"SSL-Zertifikat von DomainFactory auf IIS einbinden\",\"datePublished\":\"2017-06-13T20:08:43+00:00\",\"dateModified\":\"2017-06-24T10:28:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/ssl-zertifikat-von-domainfactory-auf-iis-einbinden\\\/\"},\"wordCount\":255,\"publisher\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\"},\"image\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/ssl-zertifikat-von-domainfactory-auf-iis-einbinden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/935.png\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/ssl-zertifikat-von-domainfactory-auf-iis-einbinden\\\/\",\"url\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/ssl-zertifikat-von-domainfactory-auf-iis-einbinden\\\/\",\"name\":\"SSL-Zertifikat von DomainFactory auf IIS einbinden\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/ssl-zertifikat-von-domainfactory-auf-iis-einbinden\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/ssl-zertifikat-von-domainfactory-auf-iis-einbinden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/935.png\",\"datePublished\":\"2017-06-13T20:08:43+00:00\",\"dateModified\":\"2017-06-24T10:28:05+00:00\",\"description\":\"In Zeiten von Let's Encrypt gelten verschl\u00fcsselte Websites inzwischen zum Standard. Doch auch Wildcard- oder Extended-Zertifikate mit besonders\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/ssl-zertifikat-von-domainfactory-auf-iis-einbinden\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vielhuber.de\\\/blog\\\/ssl-zertifikat-von-domainfactory-auf-iis-einbinden\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/ssl-zertifikat-von-domainfactory-auf-iis-einbinden\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/935.png\",\"contentUrl\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/935.png\",\"width\":881,\"height\":204},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/blog\\\/ssl-zertifikat-von-domainfactory-auf-iis-einbinden\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vielhuber.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SSL-Zertifikat von DomainFactory auf IIS einbinden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#website\",\"url\":\"https:\\\/\\\/vielhuber.de\\\/\",\"name\":\"Vielhuber David\",\"description\":\"Full-Stack Developer\",\"publisher\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vielhuber.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/vielhuber.de\\\/#\\\/schema\\\/person\\\/64d4ff14713d413ea4d9b210d0c2c6ef\",\"name\":\"David\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\",\"url\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\",\"contentUrl\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\",\"width\":700,\"height\":552,\"caption\":\"David\"},\"logo\":{\"@id\":\"https:\\\/\\\/vielhuber.de\\\/wp-content\\\/uploads\\\/about.jpg\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/vielhuber\"]}]}<\/script>","yoast_head_json":{"title":"SSL-Zertifikat von DomainFactory auf IIS einbinden","description":"In Zeiten von Let's Encrypt gelten verschl\u00fcsselte Websites inzwischen zum Standard. Doch auch Wildcard- oder Extended-Zertifikate mit besonders","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vielhuber.de\/blog\/ssl-zertifikat-von-domainfactory-auf-iis-einbinden\/","og_locale":"de_DE","og_type":"article","og_title":"SSL-Zertifikat von DomainFactory auf IIS einbinden","og_description":"In Zeiten von Let's Encrypt gelten verschl\u00fcsselte Websites inzwischen zum Standard. Doch auch Wildcard- oder Extended-Zertifikate mit besonders","og_url":"https:\/\/vielhuber.de\/blog\/ssl-zertifikat-von-domainfactory-auf-iis-einbinden\/","og_site_name":"Vielhuber David","article_published_time":"2017-06-13T20:08:43+00:00","article_modified_time":"2017-06-24T10:28:05+00:00","og_image":[{"url":"https:\/\/vielhuber.de\/wp-content\/uploads\/935.png","type":"","width":"","height":""}],"author":"David","twitter_card":"summary_large_image","twitter_creator":"@vielhuber","twitter_site":"@vielhuber","twitter_misc":{"Verfasst von":"David","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vielhuber.de\/blog\/ssl-zertifikat-von-domainfactory-auf-iis-einbinden\/#article","isPartOf":{"@id":"https:\/\/vielhuber.de\/blog\/ssl-zertifikat-von-domainfactory-auf-iis-einbinden\/"},"author":{"name":"David","@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef"},"headline":"SSL-Zertifikat von DomainFactory auf IIS einbinden","datePublished":"2017-06-13T20:08:43+00:00","dateModified":"2017-06-24T10:28:05+00:00","mainEntityOfPage":{"@id":"https:\/\/vielhuber.de\/blog\/ssl-zertifikat-von-domainfactory-auf-iis-einbinden\/"},"wordCount":255,"publisher":{"@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef"},"image":{"@id":"https:\/\/vielhuber.de\/blog\/ssl-zertifikat-von-domainfactory-auf-iis-einbinden\/#primaryimage"},"thumbnailUrl":"https:\/\/vielhuber.de\/wp-content\/uploads\/935.png","articleSection":["Blog"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/vielhuber.de\/blog\/ssl-zertifikat-von-domainfactory-auf-iis-einbinden\/","url":"https:\/\/vielhuber.de\/blog\/ssl-zertifikat-von-domainfactory-auf-iis-einbinden\/","name":"SSL-Zertifikat von DomainFactory auf IIS einbinden","isPartOf":{"@id":"https:\/\/vielhuber.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vielhuber.de\/blog\/ssl-zertifikat-von-domainfactory-auf-iis-einbinden\/#primaryimage"},"image":{"@id":"https:\/\/vielhuber.de\/blog\/ssl-zertifikat-von-domainfactory-auf-iis-einbinden\/#primaryimage"},"thumbnailUrl":"https:\/\/vielhuber.de\/wp-content\/uploads\/935.png","datePublished":"2017-06-13T20:08:43+00:00","dateModified":"2017-06-24T10:28:05+00:00","description":"In Zeiten von Let's Encrypt gelten verschl\u00fcsselte Websites inzwischen zum Standard. Doch auch Wildcard- oder Extended-Zertifikate mit besonders","breadcrumb":{"@id":"https:\/\/vielhuber.de\/blog\/ssl-zertifikat-von-domainfactory-auf-iis-einbinden\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vielhuber.de\/blog\/ssl-zertifikat-von-domainfactory-auf-iis-einbinden\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/vielhuber.de\/blog\/ssl-zertifikat-von-domainfactory-auf-iis-einbinden\/#primaryimage","url":"https:\/\/vielhuber.de\/wp-content\/uploads\/935.png","contentUrl":"https:\/\/vielhuber.de\/wp-content\/uploads\/935.png","width":881,"height":204},{"@type":"BreadcrumbList","@id":"https:\/\/vielhuber.de\/blog\/ssl-zertifikat-von-domainfactory-auf-iis-einbinden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vielhuber.de\/"},{"@type":"ListItem","position":2,"name":"SSL-Zertifikat von DomainFactory auf IIS einbinden"}]},{"@type":"WebSite","@id":"https:\/\/vielhuber.de\/#website","url":"https:\/\/vielhuber.de\/","name":"Vielhuber David","description":"Full-Stack Developer","publisher":{"@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vielhuber.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/vielhuber.de\/#\/schema\/person\/64d4ff14713d413ea4d9b210d0c2c6ef","name":"David","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg","url":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg","contentUrl":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg","width":700,"height":552,"caption":"David"},"logo":{"@id":"https:\/\/vielhuber.de\/wp-content\/uploads\/about.jpg"},"sameAs":["https:\/\/x.com\/vielhuber"]}]}},"_links":{"self":[{"href":"https:\/\/vielhuber.de\/da\/wp-json\/wp\/v2\/posts\/1590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vielhuber.de\/da\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vielhuber.de\/da\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vielhuber.de\/da\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vielhuber.de\/da\/wp-json\/wp\/v2\/comments?post=1590"}],"version-history":[{"count":14,"href":"https:\/\/vielhuber.de\/da\/wp-json\/wp\/v2\/posts\/1590\/revisions"}],"predecessor-version":[{"id":1612,"href":"https:\/\/vielhuber.de\/da\/wp-json\/wp\/v2\/posts\/1590\/revisions\/1612"}],"wp:attachment":[{"href":"https:\/\/vielhuber.de\/da\/wp-json\/wp\/v2\/media?parent=1590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vielhuber.de\/da\/wp-json\/wp\/v2\/categories?post=1590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vielhuber.de\/da\/wp-json\/wp\/v2\/tags?post=1590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}